{"id":267,"count":2,"description":"","link":"https:\/\/adamant-real-estate.com\/de\/feature\/fensterladen\/","name":"Fensterl\u00e4den","slug":"fensterladen","taxonomy":"property_feature","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fensterl\u00e4den Archives - ADAMANT REAL ESTATE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adamant-real-estate.com\/de\/feature\/fensterladen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fensterl\u00e4den Archives - ADAMANT REAL ESTATE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adamant-real-estate.com\/de\/feature\/fensterladen\/\" \/>\n<meta property=\"og:site_name\" content=\"ADAMANT REAL ESTATE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/feature\\\/fensterladen\\\/\",\"url\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/feature\\\/fensterladen\\\/\",\"name\":\"Fensterl\u00e4den Archives - ADAMANT REAL ESTATE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/feature\\\/fensterladen\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/feature\\\/fensterladen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fensterl\u00e4den\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/\",\"name\":\"ADAMANT REAL ESTATE\",\"description\":\"REAL ESTATE D\u00c9NIA COSTA BLANCA\",\"publisher\":{\"@id\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/#organization\",\"name\":\"ADAMANT REAL ESTATE\",\"url\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adamant-real-estate.com\\\/dev\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/adamant-real-estate-denia-costa-blanca-logo5.png\",\"contentUrl\":\"https:\\\/\\\/adamant-real-estate.com\\\/dev\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/adamant-real-estate-denia-costa-blanca-logo5.png\",\"width\":440,\"height\":100,\"caption\":\"ADAMANT REAL ESTATE\"},\"image\":{\"@id\":\"https:\\\/\\\/adamant-real-estate.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fensterl\u00e4den Archives - ADAMANT REAL ESTATE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adamant-real-estate.com\/de\/feature\/fensterladen\/","og_locale":"de_DE","og_type":"article","og_title":"Fensterl\u00e4den Archives - ADAMANT REAL ESTATE","og_url":"https:\/\/adamant-real-estate.com\/de\/feature\/fensterladen\/","og_site_name":"ADAMANT REAL ESTATE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/adamant-real-estate.com\/de\/feature\/fensterladen\/","url":"https:\/\/adamant-real-estate.com\/de\/feature\/fensterladen\/","name":"Fensterl\u00e4den Archives - ADAMANT REAL ESTATE","isPartOf":{"@id":"https:\/\/adamant-real-estate.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/adamant-real-estate.com\/de\/feature\/fensterladen\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/adamant-real-estate.com\/de\/feature\/fensterladen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adamant-real-estate.com\/de\/"},{"@type":"ListItem","position":2,"name":"Fensterl\u00e4den"}]},{"@type":"WebSite","@id":"https:\/\/adamant-real-estate.com\/de\/#website","url":"https:\/\/adamant-real-estate.com\/de\/","name":"ADAMANT REAL ESTATE","description":"REAL ESTATE D\u00c9NIA COSTA BLANCA","publisher":{"@id":"https:\/\/adamant-real-estate.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adamant-real-estate.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/adamant-real-estate.com\/de\/#organization","name":"ADAMANT REAL ESTATE","url":"https:\/\/adamant-real-estate.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/adamant-real-estate.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adamant-real-estate.com\/dev\/wp-content\/uploads\/2019\/08\/adamant-real-estate-denia-costa-blanca-logo5.png","contentUrl":"https:\/\/adamant-real-estate.com\/dev\/wp-content\/uploads\/2019\/08\/adamant-real-estate-denia-costa-blanca-logo5.png","width":440,"height":100,"caption":"ADAMANT REAL ESTATE"},"image":{"@id":"https:\/\/adamant-real-estate.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adamant-real-estate.com\/de\/wp-json\/wp\/v2\/property_feature\/267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adamant-real-estate.com\/de\/wp-json\/wp\/v2\/property_feature"}],"about":[{"href":"https:\/\/adamant-real-estate.com\/de\/wp-json\/wp\/v2\/taxonomies\/property_feature"}],"wp:post_type":[{"href":"https:\/\/adamant-real-estate.com\/de\/wp-json\/wp\/v2\/properties?property_feature=267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}